{"id":5601,"date":"2020-05-24T11:24:36","date_gmt":"2020-05-24T10:24:36","guid":{"rendered":"https:\/\/palmariders.com\/datenschutzbestimmungen\/"},"modified":"2024-04-03T20:44:17","modified_gmt":"2024-04-03T19:44:17","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/palmariders.com\/de\/privacy-policy\/","title":{"rendered":"Datenschutzbestimmungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5601\" class=\"elementor elementor-5601 elementor-35\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e896ea8 elementor-section-content-middle headerahora elementor-hidden-desktop elementor-hidden-laptop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e896ea8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34666f1\" data-id=\"34666f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-inner-section elementor-element elementor-element-8a6b0ca elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8a6b0ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fde8948\" data-id=\"fde8948\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f10b4b0 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f10b4b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/palmariders.com\/de\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"351\" height=\"297\" src=\"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png\" class=\"attachment-large size-large wp-image-5413\" alt=\"\" srcset=\"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png.webp 351w, https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web-300x254.png.webp 300w\" sizes=\"(max-width: 351px) 100vw, 351px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d5b5c1b elementor-hidden-desktop elementor-hidden-laptop\" data-id=\"d5b5c1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08a652 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b08a652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6NTgwNCwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"50\" viewBox=\"0 0 37.5 37.499999\" height=\"50\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"6087573a44\"><path d=\"M 0 12 L 37.007812 12 L 37.007812 15 L 0 15 Z M 0 12 \" clip-rule=\"nonzero\"><\/path><\/clipPath><clipPath id=\"5f12fe6459\"><path d=\"M 0 17 L 37.007812 17 L 37.007812 20 L 0 20 Z M 0 17 \" clip-rule=\"nonzero\"><\/path><\/clipPath><clipPath id=\"08d54b8532\"><path d=\"M 0 22 L 37.007812 22 L 37.007812 25 L 0 25 Z M 0 22 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><g clip-path=\"url(#6087573a44)\"><path stroke-linecap=\"butt\" transform=\"matrix(0.740132, 0, 0, 0.740132, 0.0000005, 12.064143)\" fill=\"none\" stroke-linejoin=\"miter\" d=\"M -0.000000675556 1.501947 L 50.001669 1.501947 \" stroke=\"#ffffff\" stroke-width=\"3\" stroke-opacity=\"1\" stroke-miterlimit=\"4\"><\/path><\/g><g clip-path=\"url(#5f12fe6459)\"><path stroke-linecap=\"butt\" transform=\"matrix(0.740132, 0, 0, 0.740132, 0.0000005, 17.393091)\" fill=\"none\" stroke-linejoin=\"miter\" d=\"M -0.000000675556 1.500835 L 50.001669 1.500835 \" stroke=\"#ffffff\" stroke-width=\"3\" stroke-opacity=\"1\" stroke-miterlimit=\"4\"><\/path><\/g><g clip-path=\"url(#08d54b8532)\"><path stroke-linecap=\"butt\" transform=\"matrix(0.740132, 0, 0, 0.740132, 0.0000005, 22.722038)\" fill=\"none\" stroke-linejoin=\"miter\" d=\"M -0.000000675556 1.499724 L 50.001669 1.499724 \" stroke=\"#ffffff\" stroke-width=\"3\" stroke-opacity=\"1\" stroke-miterlimit=\"4\"><\/path><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d2d172 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"7d2d172\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90a3a2d\" data-id=\"90a3a2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-inner-section elementor-element elementor-element-a3513c9 elementor-section-full_width elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"a3513c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-be9c471 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"be9c471\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82a6913 elementor-widget elementor-widget-heading\" data-id=\"82a6913\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/palmariders.de\">HOME<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-603778b\" data-id=\"603778b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab0f569 elementor-widget elementor-widget-heading\" data-id=\"ab0f569\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/palmariders.com\/#reserva\">RESERVIEREN<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-a68138d\" data-id=\"a68138d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89f95b0 elementor-widget elementor-widget-heading\" data-id=\"89f95b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/palmariders.com\/de\/nuestros-planes\/\">PLANEN<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-76474cb\" data-id=\"76474cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6f594b elementor-widget elementor-widget-image\" data-id=\"a6f594b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/palmariders.com\/de\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"351\" height=\"297\" src=\"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png\" class=\"attachment-large size-large wp-image-5413\" alt=\"\" srcset=\"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png.webp 351w, https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web-300x254.png.webp 300w\" sizes=\"(max-width: 351px) 100vw, 351px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-b8855ad\" data-id=\"b8855ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab72616 elementor-widget elementor-widget-heading\" data-id=\"ab72616\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/palmariders.com\/de\/quienes-somos\/\">WIR<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-0a482e3\" data-id=\"0a482e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eda57f elementor-widget elementor-widget-heading\" data-id=\"5eda57f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/palmariders.com\/de\/blog-news\/\">BLOG<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-96fba98\" data-id=\"96fba98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aca3cec elementor-widget elementor-widget-heading\" data-id=\"aca3cec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/palmariders.com\/de\/contactanos\/\">KONTAKT<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1722d81a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1722d81a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-656bb96a\" data-id=\"656bb96a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a39a6d4 elementor-widget elementor-widget-text-editor\" data-id=\"1a39a6d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<ol><li><strong><em>BENUTZERINFORMATIONEN<\/em><\/strong><br><br><strong>Wer ist der f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten Verantwortliche?<\/strong><br>Palma Riders S.C. ist verantwortlich f\u00fcr die Verarbeitung der pers\u00f6nlichen Daten des Nutzers und informiert Sie, dass diese Daten in \u00dcbereinstimmung mit den Bestimmungen der Verordnung (EU) 2016\/679 vom 27. April (GDPR) und dem Organgesetz 3\/2018 vom 5. Dezember (LOPDGDD) verarbeitet werden.<br><br><strong>Welche Art von Daten werden von uns angefordert und verarbeitet?<\/strong><br>Je nach Art und Weise der Datenerhebung erfragen wir immer nur das Minimum, das zur Erf\u00fcllung der jeweils angegebenen Zwecke erforderlich ist.<br><br><strong>Wozu verarbeiten wir Ihre personenbezogenen Daten und warum?<\/strong><br>Je nach der Form, in der wir Ihre pers\u00f6nlichen Daten erhalten haben, werden wir sie vertraulich behandeln, um unsere Zwecke zu erreichen:<br>  &#8211; <strong>Im Kontaktformular<br><\/strong>Zur Beantwortung von Anfragen oder Anfragen jeglicher Art, die vom Nutzer \u00fcber eines der folgenden Formulare gestellt werden<br>der Kontaktformulare, die Ihnen auf der Website des f\u00fcr die Verarbeitung Verantwortlichen zur Verf\u00fcgung gestellt werden.<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>Durchf\u00fchrung von statistischen Analysen und Marktforschung.<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>      <strong>&#8211; Im Newsletter-Formular<\/strong><br>Versenden Sie Newsletter, Nachrichten, Angebote und Werbeaktionen online.<br>(mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>  &#8211; <strong>Im Formular &#8222;Angebot anfordern<\/strong><br>Senden Sie kommerzielle Angebote f\u00fcr Produkte und Dienstleistungen.<br>(zur Erf\u00fcllung eines Vertrags oder eines Vorvertrags, 6.1.b GDPR)<br>  &#8211; <strong>Im Lebenslauf-Formular<\/strong><br>Einbindung des Bewerbers in den Einstellungsprozess und Analyse des Bewerberprofils mit dem Ziel<br>Ziel ist die Auswahl eines Bewerbers f\u00fcr die freie Stelle des Leiters.<br>(mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>      <strong>&#8211; In den Formularen Reservierungen<\/strong><br>Formalisieren Sie die Reservierungen im Betrieb des Verantwortlichen.<br>(zur Erf\u00fcllung eines Vertrags oder eines Vorvertrags, 6.1.b GDPR)<br>Versenden von kommerziellen Werbemitteilungen per E-Mail, Fax, SMS, MMS, in sozialen Netzwerken oder auf anderem Wege.<br>gegenw\u00e4rtige oder k\u00fcnftige elektronische oder physische Mittel f\u00fcr Kunden, die eine kommerzielle Kommunikation erm\u00f6glichen<br>Produkte oder Dienstleistungen, die denen \u00e4hnlich sind, die urspr\u00fcnglich von<br>den Kunden (Art. 21.2 LSSI). (f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>Palma Riders S.C. Palma Riders S.C. S. 2 29-09-2022<br>  &#8211; <strong>Im Formular Termine<\/strong><br>Vereinbaren Sie Termine und Besprechungen mit der zust\u00e4ndigen Person. (f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>Soziale Netzwerke<br>Kontaktaufnahme \u00fcber soziale Netzwerke, um eine Beziehung zwischen dem Nutzer und dem f\u00fcr die Verarbeitung Verantwortlichen zu unterhalten.<br>die die folgenden Vorg\u00e4nge umfassen k\u00f6nnen: &#8211; Bearbeitung Ihrer Antr\u00e4ge und Anfragen. &#8211; Berichterstattung \u00fcber Aktivit\u00e4ten<br>und Veranstaltungen. &#8211; Um \u00fcber Produkte und\/oder Dienstleistungen zu informieren. &#8211; Interaktion \u00fcber die offiziellen Profile. Der Benutzer<br>ein Profil in demselben sozialen Netzwerk hat und sich entschlossen hat, dem sozialen Netzwerk der verantwortlichen Person beizutreten, was zeigt, dass sie<br>Ihr Interesse an den darin ver\u00f6ffentlichten Informationen, daher sollten Sie bei der Beantragung der Teilnahme an unserer<br>offiziellen Website geben Sie uns Ihre Zustimmung zur Verarbeitung Ihrer Daten. Der Benutzer kann jederzeit auf folgende Informationen zugreifen<br>Datenschutzrichtlinien des sozialen Netzwerks selbst sowie die Konfiguration Ihres Profils, um Ihre Privatsph\u00e4re zu sch\u00fctzen.<br>Privatsph\u00e4re. Sobald der Nutzer ein Follower ist oder dem sozialen Netzwerk des f\u00fcr die Verarbeitung Verantwortlichen beigetreten ist, kann er\/sie im<br>dieselben Kommentare, Links, Bilder, Fotografien oder jede andere Art von Inhalten, die durch dieselben unterst\u00fctzt werden.<br>Der Nutzer muss in jedem Fall der Eigent\u00fcmer der ver\u00f6ffentlichten Inhalte sein, das Urheberrecht und die Rechte des Nutzers besitzen.<br>geistiges Eigentum oder die Zustimmung der betroffenen Dritten haben. &#8211; Versenden von Mitteilungen<br>Konzerngesellschaften sowie Unternehmen au\u00dferhalb des Konzerns mit dem Ziel, den Konzern mit den notwendigen<br>die kommerzielle Kooperations- oder Vermittlungsvereinbarungen geschlossen haben.<br>(mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>  &#8211; <strong>Instant Messaging<br><\/strong>Planen Sie Termine und Besprechungen mit der zust\u00e4ndigen Person.<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>Versenden von kommerziellen Werbemitteilungen per E-Mail, Fax, SMS, MMS, in sozialen Netzwerken oder auf anderem Wege.<br>gegenw\u00e4rtige oder k\u00fcnftige elektronische oder physische Mittel f\u00fcr Kunden, die eine kommerzielle Kommunikation erm\u00f6glichen<br>Produkte oder Dienstleistungen, die denen \u00e4hnlich sind, die urspr\u00fcnglich von<br>den Kunden (Art. 21.2 LSSI).<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>Verwaltung, Aufrechterhaltung, Verbesserung oder Entwicklung der angebotenen Dienste.<br>(zur Erf\u00fcllung eines Vertrags oder eines Vorvertrags, 6.1.b GDPR)<br>Verwalten Sie Ihren Online-Kauf oder Ihre Bestellung, bearbeiten Sie die Zahlung und fahren Sie mit dem Versand oder der Aktivierung desselben fort, basierend auf den<br>allgemeine gesch\u00e4ftsbedingungen. (zur Erf\u00fcllung eines Vertrags oder eines Vorvertrags, 6.1.b GDPR)<br>Senden Sie kommerzielle Angebote f\u00fcr Produkte und Dienstleistungen. (zur Erf\u00fcllung eines Vertrags oder eines Vorvertrags, 6.1.b GDPR)<br>Versenden von kommerziellen Werbemitteilungen per E-Mail, Fax, SMS, MMS, in sozialen Netzwerken oder auf anderem Wege.<br>gegenw\u00e4rtige oder zuk\u00fcnftige elektronische oder physische Mittel, die kommerzielle Kommunikation erm\u00f6glichen. Sie sind bei<br>Die Mitteilungen erfolgen durch den f\u00fcr die Verarbeitung Verantwortlichen und beziehen sich auf seine Produkte und Dienstleistungen oder auf<br>seine Mitarbeiter oder Lieferanten, mit denen es eine Werbevereinbarung getroffen hat. In diesem Fall,<br>Dritte werden niemals Zugang zu personenbezogenen Daten haben. (mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>Beantwortung von Anfragen oder Anfragen jeglicher Art, die vom Nutzer \u00fcber einen der folgenden Kan\u00e4le gestellt werden<br>der Kontaktformulare, die Ihnen auf der Website des f\u00fcr die Verarbeitung Verantwortlichen zur Verf\u00fcgung gestellt werden.<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>  &#8211; <strong>Video\u00fcberwachung<\/strong><br>Palma Riders S.C.<br>Palma Riders S.C. S. 3 29-09-2022<br>Zweck Sicherheit und Zugangskontrolle, Arbeits- und interne T\u00e4tigkeitskontrolle Legitimation \u00d6ffentliches Interesse<br>f\u00fcr die Sicherheit und Zugangskontrolle und das berechtigte Interesse des f\u00fcr die Verarbeitung Verantwortlichen auf der Grundlage von Artikel 20.3 des Statuts zum Schutz der Menschenrechte und Grundfreiheiten.<br>Konservierung von Arbeitnehmern H\u00f6chstens 30 Tage<br>(mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>  &#8211; <strong>Bilder und Aufnahmen<\/strong><br>Datei mit statischen und\/oder dynamischen Bildern. Dazu geh\u00f6rt auch die Ver\u00f6ffentlichung in den Medien der Person, die f\u00fcr<br>Behandlung oder von Dritten.<br>(mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>  &#8211; <strong>Kunden und Lieferanten<\/strong><br>Handelsmanagement mit Kunden und Lieferanten<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>  &#8211; <strong>Ausschluss von Werbung<\/strong><br>Datenverwaltung, um die Zusendung kommerzieller Mitteilungen an Personen zu verhindern, die dies ausdr\u00fccklich gew\u00fcnscht haben.<br>die Verweigerung oder der Widerstand, sie zu empfangen.<br>(zur Erf\u00fcllung einer rechtlichen Verpflichtung, 6.1.c GDPR)<br>  &#8211; <strong>Kommerzielle Werbung<br><\/strong>Werbemanagement und Akquise. Enth\u00e4lt Daten aus legitimen, \u00f6ffentlich zug\u00e4nglichen Quellen.<br>(f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>  &#8211; <strong>Rechte der betroffenen Parteien<\/strong><br>Beantwortung von Ersuchen der B\u00fcrger zur Aus\u00fcbung ihrer Rechte gem\u00e4\u00df der Datenschutz-Grundverordnung<br>(zur Erf\u00fcllung einer rechtlichen Verpflichtung, 6.1.c GDPR) Web, App und andere Plattformen der verantwortlichen Partei Nutzer<br>Identifizierungsdaten von Nutzern, die auf die Unternehmenswebsite zugreifen. (f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>Schulungen, Kurse, Workshops, Aktivit\u00e4ten oder \u00c4hnliches<br>Verwaltung der Zugangs- und Benutzungsbedingungen. (f\u00fcr das berechtigte Interesse des f\u00fcr die Datenverarbeitung Verantwortlichen, Art. 6.1.f GDPR)<br>  &#8211; <strong>Wifi-Netzwerkverbindung<\/strong><br>&#8211; Durchf\u00fchrung von statistischen Analysen und Marktforschung. ( f\u00fcr das berechtigte Interesse des f\u00fcr die Verarbeitung Verantwortlichen, Art. 6.1.f GDPR )<br>&#8211; Durchf\u00fchrung von Zufriedenheits- und Qualit\u00e4tsumfragen. ( f\u00fcr das berechtigte Interesse des f\u00fcr die Verarbeitung Verantwortlichen, Art. 6.1.f GDPR )<br>(mit Zustimmung der betroffenen Person, 6.1.a GDPR)<br>Wie lange werden wir Ihre personenbezogenen Daten aufbewahren?<br>Sie werden nur so lange aufbewahrt, wie es f\u00fcr die Aufrechterhaltung des Zwecks der Verarbeitung erforderlich ist oder wie es gesetzliche Vorschriften vorschreiben, die ihre Aufbewahrung vorschreiben, und wenn sie f\u00fcr diesen Zweck nicht mehr erforderlich sind, werden sie mit geeigneten Sicherheitsma\u00dfnahmen gel\u00f6scht, um die Anonymisierung der Daten oder ihre vollst\u00e4ndige Vernichtung zu gew\u00e4hrleisten.<br>Palma Riders S.C.<br>Palma Riders S.C. S. 4 29-09-2022<br><br><strong>An wen geben wir Ihre personenbezogenen Daten weiter?<\/strong><br>Eine Weitergabe personenbezogener Daten an Dritte ist nicht vorgesehen, es sei denn, sie ist f\u00fcr die Entwicklung und Durchf\u00fchrung der Aktivit\u00e4ten erforderlich, und zwar in dem Ma\u00dfe, wie es notwendig ist, um<br>f\u00fcr die Zwecke der Verarbeitung, an unsere Kommunikationsdienstleister, mit denen der f\u00fcr die Verarbeitung Verantwortliche<br>die nach den geltenden Datenschutzbestimmungen erforderlichen Vertraulichkeits- und Datenverarbeitungsvertr\u00e4ge unterzeichnet hat.<br><br><strong>F\u00fchren wir internationale \u00dcberweisungen durch?<\/strong><br>Gem\u00e4\u00df den Bestimmungen von Artikel 44 der Datenschutz-Grundverordnung muss die Genehmigung der internationalen \u00dcbermittlung von Daten an<br>ein Land, das nicht zu einem Land mit einem angemessenen Schutzniveau erkl\u00e4rt wurde, kann nur gew\u00e4hrt werden, wenn sie<br>ausreichende Garantien. Sie kann daher gew\u00e4hrt werden, wenn der f\u00fcr die Verarbeitung Verantwortliche einen schriftlichen Vertrag vorlegt, der zwischen ihm und dem f\u00fcr die Verarbeitung Verantwortlichen geschlossen wurde.<br>den Datenexporteur und den Datenimporteur, die die erforderlichen Garantien f\u00fcr die Einhaltung des Schutzes personenbezogener Daten enthalten.<br>und die Aus\u00fcbung ihrer Rechte gew\u00e4hrleistet ist.<br>Die verantwortliche Partei kann Dienste von Anbietern in Anspruch nehmen, die Server oder Standorte an anderen Orten haben und sich an anderen Orten befinden k\u00f6nnen,<br>Diese \u00dcberweisungen sind daher vorzunehmen. Eine aktuelle Liste der Anbieter finden Sie in der<br>verantwortlich oder \u00fcber palmariders@gmail.com<br><br><strong>Welche Rechte haben Sie?<\/strong><br>Die Rechte des Benutzers sind wie folgt:<br>Recht auf jederzeitigen Widerruf der Einwilligung.<br>Das Recht auf Zugang, Berichtigung, \u00dcbertragbarkeit und L\u00f6schung Ihrer Daten sowie das Recht, die Verarbeitung einzuschr\u00e4nken oder abzulehnen.<br>Das Recht, eine Beschwerde bei der Aufsichtsbeh\u00f6rde (www.aepd.es) einzureichen, wenn Sie der Ansicht sind, dass die Verarbeitung nicht im Einklang mit dem Gesetz erfolgt.<br>mit den geltenden Vorschriften \u00fcbereinstimmt.<br>Kontaktdaten f\u00fcr die Wahrnehmung Ihrer Rechte:<br>Palma Riders S.C.. C\/ Arxiduc Llu\u00eds Salvador, 19, Local Izq., &#8211; 07004 Palma de Mallorca (Illes Balears). E-Mail: palmariders@palmariders<br><\/li><li><strong><em>OBLIGATORISCHER ODER FAKULTATIVER CHARAKTER DER VOM NUTZER BEREITGESTELLTEN INFORMATIONEN<\/em><\/strong><br>Mit dem Ankreuzen der entsprechenden K\u00e4stchen und der Eingabe von Daten in die mit einem Sternchen (*) gekennzeichneten Felder im Kontaktformular oder in den Download-Formularen akzeptieren die Nutzer ausdr\u00fccklich und frei und unmissverst\u00e4ndlich, dass ihre Daten f\u00fcr die Erf\u00fcllung ihrer Anfrage durch den Anbieter erforderlich sind, wobei die Angabe der Daten freiwillig ist.<br>in den \u00fcbrigen Feldern. Der Nutzer garantiert, dass die pers\u00f6nlichen Daten, die er dem f\u00fcr die Verarbeitung Verantwortlichen zur Verf\u00fcgung gestellt hat, der Wahrheit entsprechen, und ist daf\u00fcr verantwortlich, etwaige \u00c4nderungen mitzuteilen.<br>Der Verantwortliche weist darauf hin, dass alle \u00fcber die Website angeforderten Daten obligatorisch sind, da sie f\u00fcr die Bereitstellung eines optimalen Dienstes f\u00fcr den Benutzer erforderlich sind. Wenn nicht alle Daten angegeben werden, kann nicht garantiert werden, dass die angebotenen Informationen und Dienstleistungen vollst\u00e4ndig auf Ihre Bed\u00fcrfnisse zugeschnitten sind.<br>Wenn Sie uns auf irgendeine Weise personenbezogene Daten anderer Personen zur Verf\u00fcgung stellen, weist der Verantwortliche darauf hin, dass Sie dies mit deren Einverst\u00e4ndnis tun m\u00fcssen und uns zuvor \u00fcber die in dieser Datenschutzrichtlinie enthaltenen Punkte informiert haben. Ebenso verpflichtet sich der Verantwortliche, jedem Dritten, dessen Daten er uns zur Verf\u00fcgung stellt, die Informationen mitzuteilen, die sich daraus ergeben k\u00f6nnen<br>Es gelten die einschl\u00e4gigen Bestimmungen von Artikel 14 der Allgemeinen Verfahrensordnung.<br>Palma Riders S.C.<br>Palma Riders S.C. S. 5 29-09-2022<br><\/li><li><strong><em>SICHERHEITSMASSNAHMEN<\/em><\/strong><br>dass der f\u00fcr die Verarbeitung Verantwortliche in \u00dcbereinstimmung mit den geltenden Vorschriften zum Schutz personenbezogener Daten alle Bestimmungen der DSGVO und der LOPDGDD f\u00fcr die Verarbeitung personenbezogener Daten unter seiner Verantwortung einh\u00e4lt und die in Artikel 5 der DSGVO beschriebenen Grunds\u00e4tze offenkundig einh\u00e4lt, wonach die Daten rechtm\u00e4\u00dfig, nach Treu und Glauben und in transparenter Weise gegen\u00fcber der betroffenen Person verarbeitet werden und den Zwecken, f\u00fcr die sie verarbeitet werden, entsprechen, daf\u00fcr erheblich sind und auf das erforderliche Ma\u00df beschr\u00e4nkt sind.<br>Der Verantwortliche garantiert, dass er geeignete technische und organisatorische Ma\u00dfnahmen zur Anwendung der von der DSGVO und der LOPDGDD festgelegten Sicherheitsma\u00dfnahmen ergriffen hat, um die Rechte und Freiheiten der Nutzer zu sch\u00fctzen, und dass er ihnen die entsprechenden Informationen zur Verf\u00fcgung stellt, damit sie diese wahrnehmen k\u00f6nnen.<br>F\u00fcr weitere Informationen \u00fcber Datenschutzgarantien, k\u00f6nnen Sie die verantwortliche Person durch Palma Riders S.C. kontaktieren. C\/ Arxiduc Llu\u00eds Salvador, 19, Local Izq., &#8211; 07004 Palma de Mallorca (Illes Balears). E-Mail: palmariders@palmariders<br><\/li><li><strong><em>VALIDIT\u00c4T<\/em><\/strong><br>Diese Datenschutzrichtlinie gilt ab dem 29\/09\/2022<br>Die verantwortliche Partei beh\u00e4lt sich das Recht vor, diese Politik zu \u00e4ndern, um sie an k\u00fcnftige Aktualisierungen von Gesetzen oder Vorschriften anzupassen.<br>der geltenden Rechtsprechung oder aus anderen technischen, betrieblichen, kommerziellen, unternehmerischen usw. Gr\u00fcnden. Wenn durch die \u00c4nderungen die Rechte der Nutzer beeintr\u00e4chtigt werden, verpflichtet sich die verantwortliche Partei, \u00fcber die Gr\u00fcnde daf\u00fcr zu informieren.<\/li><\/ol>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HOME RESERVIEREN PLANEN WIR BLOG KONTAKT BENUTZERINFORMATIONEN Wer ist der f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten Verantwortliche?Palma Riders S.C. ist verantwortlich f\u00fcr die Verarbeitung der pers\u00f6nlichen Daten des Nutzers und informiert Sie, dass diese Daten in \u00dcbereinstimmung mit den Bestimmungen der Verordnung (EU) 2016\/679 vom 27. April (GDPR) und dem Organgesetz 3\/2018 vom 5. Dezember<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-5601","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzbestimmungen - Palma Riders<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palmariders.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzbestimmungen - Palma Riders\" \/>\n<meta property=\"og:description\" content=\"HOME RESERVIEREN PLANEN WIR BLOG KONTAKT BENUTZERINFORMATIONEN Wer ist der f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten Verantwortliche?Palma Riders S.C. ist verantwortlich f\u00fcr die Verarbeitung der pers\u00f6nlichen Daten des Nutzers und informiert Sie, dass diese Daten in \u00dcbereinstimmung mit den Bestimmungen der Verordnung (EU) 2016\/679 vom 27. April (GDPR) und dem Organgesetz 3\/2018 vom 5. Dezember\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palmariders.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Palma Riders\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/palmariders\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-03T19:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/\",\"name\":\"Datenschutzbestimmungen - Palma Riders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palmariders.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/palmariders.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-2022-blanco-para-web.png\",\"datePublished\":\"2020-05-24T10:24:36+00:00\",\"dateModified\":\"2024-04-03T19:44:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/palmariders.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-2022-blanco-para-web.png\",\"contentUrl\":\"https:\\\/\\\/palmariders.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-2022-blanco-para-web.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palmariders.com\\\/de\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/palmariders.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzbestimmungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palmariders.com\\\/#website\",\"url\":\"https:\\\/\\\/palmariders.com\\\/\",\"name\":\"https:\\\/\\\/palmariders.com\\\/\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palmariders.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzbestimmungen - Palma Riders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palmariders.com\/de\/privacy-policy\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzbestimmungen - Palma Riders","og_description":"HOME RESERVIEREN PLANEN WIR BLOG KONTAKT BENUTZERINFORMATIONEN Wer ist der f\u00fcr die Verarbeitung Ihrer personenbezogenen Daten Verantwortliche?Palma Riders S.C. ist verantwortlich f\u00fcr die Verarbeitung der pers\u00f6nlichen Daten des Nutzers und informiert Sie, dass diese Daten in \u00dcbereinstimmung mit den Bestimmungen der Verordnung (EU) 2016\/679 vom 27. April (GDPR) und dem Organgesetz 3\/2018 vom 5. Dezember","og_url":"https:\/\/palmariders.com\/de\/privacy-policy\/","og_site_name":"Palma Riders","article_publisher":"https:\/\/www.facebook.com\/palmariders\/","article_modified_time":"2024-04-03T19:44:17+00:00","og_image":[{"url":"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palmariders.com\/de\/privacy-policy\/","url":"https:\/\/palmariders.com\/de\/privacy-policy\/","name":"Datenschutzbestimmungen - Palma Riders","isPartOf":{"@id":"https:\/\/palmariders.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palmariders.com\/de\/privacy-policy\/#primaryimage"},"image":{"@id":"https:\/\/palmariders.com\/de\/privacy-policy\/#primaryimage"},"thumbnailUrl":"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png","datePublished":"2020-05-24T10:24:36+00:00","dateModified":"2024-04-03T19:44:17+00:00","breadcrumb":{"@id":"https:\/\/palmariders.com\/de\/privacy-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palmariders.com\/de\/privacy-policy\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/palmariders.com\/de\/privacy-policy\/#primaryimage","url":"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png","contentUrl":"https:\/\/palmariders.com\/wp-content\/uploads\/2024\/03\/logo-2022-blanco-para-web.png"},{"@type":"BreadcrumbList","@id":"https:\/\/palmariders.com\/de\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/palmariders.com\/"},{"@type":"ListItem","position":2,"name":"Datenschutzbestimmungen"}]},{"@type":"WebSite","@id":"https:\/\/palmariders.com\/#website","url":"https:\/\/palmariders.com\/","name":"https:\/\/palmariders.com\/","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palmariders.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/pages\/5601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/comments?post=5601"}],"version-history":[{"count":0,"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/pages\/5601\/revisions"}],"wp:attachment":[{"href":"https:\/\/palmariders.com\/de\/wp-json\/wp\/v2\/media?parent=5601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}